{"id":8920,"date":"2021-03-08T11:32:37","date_gmt":"2021-03-08T10:32:37","guid":{"rendered":"https:\/\/www.artinterview.com\/?post_type=critique&#038;p=8920"},"modified":"2023-10-10T15:16:37","modified_gmt":"2023-10-10T13:16:37","slug":"au-commencement-la-beaute","status":"publish","type":"critique","link":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/","title":{"rendered":"Au commencement la beaut\u00e9"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg\" alt=\"\" class=\"wp-image-8279\" style=\"width:232px;height:381px\" width=\"232\" height=\"381\" srcset=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg 518w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125-183x300.jpg 183w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading\" id=\"block-b6e07dfd-be4e-4f89-ad08-42170d997ea0\">Extrait<br><em>Au commencement la<\/em> <em>beaut\u00e9<\/em> <em>De Chauvet \u00e0 Lascaux<\/em> de Fran\u00e7ois Warin<\/h4>\n<\/div><\/div>\n\n\n\n<p><strong>Les mains d&#8217;or <\/strong><br><br>Rares sont les philosophes qui se sont int\u00e9ress\u00e9s a ce que, depuis plus d&#8217;un si\u00e8cle, on appelle la Pr\u00e9histoire. La philosophie n&#8217;aurait-elle rien a dire sur ses d\u00e9couvertes, et notamment sur les stup\u00e9fiantes \u00ab&nbsp;inventions&nbsp;\u00bb des fresques animali\u00e8res des grottes orn\u00e9es du pal\u00e9olithique qui bouleversent les assises de I&#8217;homme occidental et remettent en cause un \u00e9volutionnisme faisant souvent corps avec un humanisme qui a install\u00e9 l\u2019homme au centre du monde ?&nbsp;<\/p>\n\n\n\n<p>Contre toute attente et au rebours de toute id\u00e9ologie anthropocentr\u00e9e, les premi\u00e8res mains du premier homme \u00e9taient d\u00e9j\u00e0 des mains d&#8217;or, et c\u2019est la parade sauvage, la splendeur de l\u2019animalit\u00e9, qu&#8217;elles avaient choisi, exclusivement, de repr\u00e9senter. La figure humaine \u00e9tait exclue et l\u2019homme pr\u00e9sent par l\u2019image m\u00e9tonymique de son propre corps faisait le \u00ab&nbsp;portrait de l\u2019homme en main&nbsp;\u00bb.<\/p>\n\n\n\n<p>Cette \u00e9nigme est au coeur de ce livre, qui a choisi simplement de se laisser surprendre et d\u2019examiner les r\u00e9ponses tr\u00e8s \u00ab&nbsp;risqu\u00e9es&nbsp;\u00bb que, depuis ses d\u00e9buts, la Pr\u00e9histoire, en proie a une sorte de fi\u00e8vre interpr\u00e9tative, a pu donner, quitte a faire oublier qu&#8217;on \u00e9tait la devant des \u00ab&nbsp;oeuvres d&#8217;art&nbsp;\u00bb dont le style demandait a \u00eatre caract\u00e9ris\u00e9.&nbsp;<\/p>\n\n\n\n<p>C\u2019est donc a travers l\u2019\u00e9paisseur de notre culture et de l\u2019histoire de la pens\u00e9e que l\u2019\u00e9nigme est examin\u00e9e, interrog\u00e9e, mise en r\u00e9sonance et en perspective. Faire le choix de s&#8217;\u00e9tonner, de vivre dans la profondeur de l\u2019\u00e9nigme, ne pas se soucier du fil d&#8217; Ariane qui cherche une issue, mais habiter la caverne, haut lieu de notre imaginaire, pourrait bien \u00eatre le propre de la philosophie.&nbsp;<\/p>\n\n\n\n<p><strong>Premi\u00e8res mains<\/strong><\/p>\n\n\n\n<p>\u00ab&nbsp;Premi\u00e8res mains&nbsp;\u00bb marque d&#8217;entr\u00e9e de jeu un \u00e9tonnement et fait \u00e9clater un paradoxe, pointe une formidable \u00e9nigme : premier, adjectif num\u00e9ral ordinal marque le rang, indique l\u2019ordre. Or ce qui vient au commencement n&#8217;est pas ce qu&#8217;il y a de plus faible, de plus ind\u00e9termin\u00e9, de plus pauvre comme le pensait Hegel, d&#8217;accord ici avec toute une tradition \u00e9volutionniste mais bien, selon Heidegger, ce qu&#8217;il y a \u00ab&nbsp;de plus violent et de plus inqui\u00e9tant&nbsp;\u00bb. La premi\u00e8re main n&#8217;est pas la main malhabile, t\u00e2tonnante ou enfantine mais la main de maitre. Au mod\u00e8le scalaire, dans la chronologie, le terme premier ajoute ici l\u2019id\u00e9e d&#8217;excellence, de sup\u00e9riorit\u00e9 de rang, il op\u00e8re un renversement de hi\u00e9rarchie. \u00ab&nbsp;La peinture est en d\u00e9cadence depuis l\u2019\u00e2ge des cavernes&nbsp;\u00bb, dira Mir\u00f3.<\/p>\n\n\n\n<p><em>Homo sapiens<\/em> venait a peine d&#8217;arriver en Europe que d\u00e9j\u00e0, \u00e0 cette extr\u00e9mit\u00e9 du temps, l\u2019homme \u00e9tait la, tout entier pr\u00e9sent. \u00c9vanouissement. annulation, court-circuit de la chronologie, voil\u00e0 qu&#8217;il laisse son empreinte volontaire et irr\u00e9cusable, son anonyme signature, et qu&#8217;il donne la preuve \u00e9mouvante, sensible que nous avons l\u00e0, tout proches, des semblables et des fr\u00e8res. L\u2019occasion pour nous de tenter \u00e0 nos risques et p\u00e9rils, quel que soit l\u2019h\u00e9ritage d&#8217;un art qui a depuis longtemps commenc\u00e9, de faire le r\u00e9cit d\u2019une fondation, de nous rapporter \u00e0 l\u2019origine et au commencement, d\u2019\u00eatre du saut ou du bond et de dire une nouvelle fois : <em>en arch\u00e8, am Anfang<\/em>, au commencement&#8230;&nbsp;<\/p>\n\n\n\n<p>En nommant ainsi, non le d\u00e9but ou le point z\u00e9ro priv\u00e9 de source mais l\u2019origine qui efface ses traces et s&#8217;affirme <em>ex nihilo<\/em>, le moment fr\u00e9missant de rupture o\u00f9 l\u2019art atteint sa pl\u00e9nitude, le moment du <em>surgissement<\/em> et du <em>r\u00e8gne<\/em>, toujours en avance sur nous. \u00ab&nbsp;Maitresse, Divine, Ouverture sans mesure&nbsp;\u00bb, \u00e9crivait Pindare.&nbsp;<\/p>\n\n\n\n<p>Ce n&#8217;est rien moins que la tradition des Lumi\u00e8res, celle qui, son nom l\u2019indique, nous aurait sortis des t\u00e9n\u00e8bres, et a laquelle notre civilisation adh\u00e9rait, qui a \u00e9t\u00e9 retourn\u00e9e comme un gant et de fa\u00e7on d\u00e9finitive avec la d\u00e9couverte des grottes orn\u00e9es. L\u2019invention de la grotte Chauvet en particulier pronon\u00e7a l\u2019arr\u00eat de mort de la sp\u00e9culation, provoqua l\u2019effondrement des chronologies patiemment \u00e9difi\u00e9es, d\u00e9clencha l\u2019interruption, la suspension, l\u2019arr\u00eat du sens et du mythe progressiste dont notre civilisation pouvait hier encore s&#8217;enorgueillir.&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><br><em><strong>Docteur en philosophie, Fran\u00e7ois Warin a enseign\u00e9 au Br\u00e9sil, en Afrique du Nord et Afrique subsaharienne. Il a publi\u00e9 de nombreux livres sur l\u2019esth\u00e9tique des arts premiers. <\/strong><\/em><\/h5>\n\n\n\n<p><br><strong>Lire plus&#8230;<\/strong><br><a rel=\"noreferrer noopener\" href=\"https:\/\/www.librairiesindependantes.com\/product\/9782363082299\/\" target=\"_blank\">Trouver en librairie<\/a> <\/p>\n\n\n\n<p><strong><em>Au commencement la beaut\u00e9<\/em><\/strong><br><em>De Chauvet \u00e0 Lascaux<\/em><br>Fran\u00e7ois Warin<br><strong>Editions Arl\u00e9a<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Le beau qui ravit et ravage, ce qui se manifeste avec une force \u00e9clatante, \u00e9tait bien l\u00e0 d\u00e8s le d\u00e9but, au commencement. Et c\u2019est ce qui nous reste du commencement.<br>La d\u00e9couverte de l\u2019art pal\u00e9olithique, de Chauvet et de Lascaux, est un moment de rupture et de surgissement. L\u2019id\u00e9e de progr\u00e8s dont notre civilisation pouvait s\u2019enorgueillir a \u00e9t\u00e9 retourn\u00e9 comme un gant, et les assises m\u00eames de l\u2019homme occidental boulevers\u00e9es.<br>La premi\u00e8re manifestation, les premi\u00e8res mains du \u00ab&nbsp;premier homme&nbsp;\u00bb, \u00e9taient d\u00e9j\u00e0 des \u00ab&nbsp;mains d\u2019or&nbsp;\u00bb, et c\u2019est la splendeur de l\u2019animalit\u00e9 qu\u2019elles avaient choisie de repr\u00e9senter.<br><br>En regardant leurs mains \u00e9tal\u00e9es et offertes, qui ne montrent, ne prennent, ne saisissent rien et peut-\u00eatre ne signifient rien, nous sommes devant la bouleversante \u00e9nigme qui est au c\u0153ur du livre de Fran\u00e7ois Warin.<\/h5>\n","protected":false},"featured_media":8279,"template":"","class_list":["post-8920","critique","type-critique","status-publish","has-post-thumbnail","hentry","categorie_crit-litterature"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Au commencement la beaut\u00e9 - Art Interview<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au commencement la beaut\u00e9 - Art Interview\" \/>\n<meta property=\"og:description\" content=\"ExtraitAu commencement la beaut\u00e9 De Chauvet \u00e0 Lascaux de Fran\u00e7ois Warin Les mains d&#8217;or Rares sont les philosophes qui se sont int\u00e9ress\u00e9s a ce que, depuis plus d&#8217;un si\u00e8cle, on appelle la Pr\u00e9histoire. La philosophie n&#8217;aurait-elle rien a dire sur ses d\u00e9couvertes, et notamment sur les stup\u00e9fiantes \u00ab&nbsp;inventions&nbsp;\u00bb des fresques animali\u00e8res des grottes orn\u00e9es du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/\" \/>\n<meta property=\"og:site_name\" content=\"Art Interview\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/artinterviewmagazine\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T13:16:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"518\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/\",\"url\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/\",\"name\":\"Au commencement la beaut\u00e9 - Art Interview\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/livreon1125.jpg\",\"datePublished\":\"2021-03-08T10:32:37+00:00\",\"dateModified\":\"2023-10-10T13:16:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/livreon1125.jpg\",\"contentUrl\":\"https:\\\/\\\/artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/livreon1125.jpg\",\"width\":518,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/au-commencement-la-beaute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/artinterview.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Critique\",\"item\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Au commencement la beaut\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/artinterview.com\\\/en\\\/\",\"name\":\"Art Interview\",\"description\":\"Because art is everywhere\",\"publisher\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artinterview.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#organization\",\"name\":\"Art Interview\",\"url\":\"https:\\\/\\\/artinterview.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/5c337d0326d4de5bde65529a.png\",\"contentUrl\":\"https:\\\/\\\/www.artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/5c337d0326d4de5bde65529a.png\",\"width\":3397,\"height\":2374,\"caption\":\"Art Interview\"},\"image\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/artinterviewmagazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/art.interview\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCjnghW7ZyDAts9yGi-Ic19w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Au commencement la beaut\u00e9 - Art Interview","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/","og_locale":"en_US","og_type":"article","og_title":"Au commencement la beaut\u00e9 - Art Interview","og_description":"ExtraitAu commencement la beaut\u00e9 De Chauvet \u00e0 Lascaux de Fran\u00e7ois Warin Les mains d&#8217;or Rares sont les philosophes qui se sont int\u00e9ress\u00e9s a ce que, depuis plus d&#8217;un si\u00e8cle, on appelle la Pr\u00e9histoire. La philosophie n&#8217;aurait-elle rien a dire sur ses d\u00e9couvertes, et notamment sur les stup\u00e9fiantes \u00ab&nbsp;inventions&nbsp;\u00bb des fresques animali\u00e8res des grottes orn\u00e9es du [&hellip;]","og_url":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/","og_site_name":"Art Interview","article_publisher":"https:\/\/www.facebook.com\/artinterviewmagazine\/","article_modified_time":"2023-10-10T13:16:37+00:00","og_image":[{"width":518,"height":850,"url":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/","url":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/","name":"Au commencement la beaut\u00e9 - Art Interview","isPartOf":{"@id":"https:\/\/artinterview.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/#primaryimage"},"image":{"@id":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/#primaryimage"},"thumbnailUrl":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg","datePublished":"2021-03-08T10:32:37+00:00","dateModified":"2023-10-10T13:16:37+00:00","breadcrumb":{"@id":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/#primaryimage","url":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg","contentUrl":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/11\/livreon1125.jpg","width":518,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/artinterview.com\/en\/critique\/au-commencement-la-beaute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/artinterview.com\/en\/"},{"@type":"ListItem","position":2,"name":"Critique","item":"https:\/\/artinterview.com\/en\/critique\/"},{"@type":"ListItem","position":3,"name":"Au commencement la beaut\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/artinterview.com\/en\/#website","url":"https:\/\/artinterview.com\/en\/","name":"Art Interview","description":"Because art is everywhere","publisher":{"@id":"https:\/\/artinterview.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artinterview.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/artinterview.com\/en\/#organization","name":"Art Interview","url":"https:\/\/artinterview.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artinterview.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.artinterview.com\/wp-content\/uploads\/2020\/04\/5c337d0326d4de5bde65529a.png","contentUrl":"https:\/\/www.artinterview.com\/wp-content\/uploads\/2020\/04\/5c337d0326d4de5bde65529a.png","width":3397,"height":2374,"caption":"Art Interview"},"image":{"@id":"https:\/\/artinterview.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/artinterviewmagazine\/","https:\/\/www.instagram.com\/art.interview\/","https:\/\/www.youtube.com\/channel\/UCjnghW7ZyDAts9yGi-Ic19w"]}]}},"_links":{"self":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/critique\/8920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/critique"}],"about":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/types\/critique"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/media\/8279"}],"wp:attachment":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/media?parent=8920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}