{"id":7095,"date":"2020-04-01T16:09:09","date_gmt":"2020-04-01T14:09:09","guid":{"rendered":"https:\/\/www.artinterview.com\/?post_type=critique&#038;p=7095"},"modified":"2022-12-31T13:05:29","modified_gmt":"2022-12-31T12:05:29","slug":"un-hans-hartung-fun-et-gestuel","status":"publish","type":"critique","link":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/","title":{"rendered":"Un Hans Hartung fun et gestuel !"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"320\" src=\"https:\/\/www.artinterview.com\/wp-content\/uploads\/2020\/04\/hartung_3-1024x320.jpg\" alt=\"\" class=\"wp-image-7300\" srcset=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/hartung_3-1024x320.jpg 1024w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/hartung_3-300x94.jpg 300w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/hartung_3-768x240.jpg 768w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/hartung_3-1536x480.jpg 1536w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/hartung_3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em><strong>L\u2019oeil du peintre Marc Goldstain<\/strong><\/em><\/p>\n\n\n\n<p>Quelques r\u00e9flexions que je partage avec vous apr\u00e8s\navoir visit\u00e9 l\u2019exposition \u00ab&nbsp;Hans Hartung et la fabrique du geste&nbsp;\u00bb au\nMus\u00e9e d\u2019art moderne de la ville de Paris, fra\u00eechement r\u00e9ouvert. Hans Hartung y\nappara\u00eet d\u00e9j\u00e0 comme un artiste contemporain sous certains aspects comme le\nchoix de ses couleurs et de ses outils. De plus, le titre de l\u2019exposition\nsugg\u00e8re son point fort&nbsp;: ses recherches d \u00ab&nbsp;\u00e9critures\ndessin\u00e9es&nbsp;\u00bb (donc le geste). Il n\u2019est pas seul \u00e0 chercher dans cette\ndirection \u00e0 son \u00e9poque&nbsp;: Mathieu, Bazaine, Soulages semblent sur des\nchemins proches\u2026 Mais Hartung est sans cesse \u00e0 la recherche de nouvelles\nformes. Celles aux traits tranch\u00e9s contrastant avec la couleur projet\u00e9e\nformeront un corpus tr\u00e8s reconnaissable.<\/p>\n\n\n\n<p>Jeune peintre, je voyais Hartung comme un de ces\nartistes \u00ab&nbsp;des ann\u00e9es cinquante&nbsp;\u00bb associ\u00e9s \u00e0 une recherche globale et\npassionnante reliant corps et \u00e2me dans une intensit\u00e9 de l\u2019instant. J\u2019y mettais\np\u00eale-m\u00eale Masson, Fautrier, Zao Wou-ki, de Kooning, Pollock\u2026 J\u2019avais lu les\nentretiens de Georges Charbonnier* avec ces artistes, et tout ce qui \u00e9tait dit\nme semblait couler de source, bien que le ton fut solennel (un go\u00fbt trop\nprononc\u00e9 pour le drame peut-\u00eatre d\u00fb \u00e0 l\u2019apr\u00e8s-guerre). <\/p>\n\n\n\n<p>Il est vrai qu\u2019on ne peut reprocher \u00e0 l\u2019artiste\nd\u2019\u00eatre engag\u00e9 dans son \u0153uvre et de viser la profondeur. L\u2019\u0153uvre d\u2019Hartung\nattire par la multiplicit\u00e9 parfois \u00e9tonnante, presqu\u2019amusante de ses\nexp\u00e9rimentations&nbsp;picturales tr\u00e8s lisibles, vives et rythm\u00e9es. Elles portent\nsur ses diff\u00e9rentes \u00e9critures dessin\u00e9es et sur toute la gamme d\u2019outils de plus\nen plus d\u00e9velopp\u00e9e, un vrai catalogue d\u2019une enseigne de bricolage&nbsp;! De l\u00e0\n\u00e0 voir un aspect ludique \u00e0 sa recherche, il n\u2019y a qu\u2019un pas.<\/p>\n\n\n\n<p>Le c\u0153ur de son travail, pr\u00e9c\u00e9dant la couleur et la\nforme, concerne l\u2019expressivit\u00e9 de son geste d\u00e9shabill\u00e9 de toute volont\u00e9 de\nfiguration. En effet, peindre de mani\u00e8re abstraite permet de mettre l\u2019accent\nsur la ligne comme trace, avant m\u00eame d\u2019y voir une forme. On parle alors de\npeinture gestuelle abstraite, d\u2019abstraction lyrique\u2026<\/p>\n\n\n\n<p>Quant \u00e0 l\u2019exposition, d\u00e8s l\u2019entr\u00e9e, la commissaire\ninscrit Hartung dans l\u2019histoire de l\u2019art par deux \u0153uvres repr\u00e9sentatives\nd\u2019\u00e9poques diff\u00e9rentes et qui se r\u00e9pondent. La premi\u00e8re est une toile de\njeunesse tr\u00e8s \u00ab&nbsp;post cubiste&nbsp;\u00bb aux tons sourds et neutres ainsi\nqu\u2019aux formes simples mais bien compos\u00e9es (Leucate, ma cabane grise 1927). <em>Au\npassage, je me dis que le gris \u00e9tait dans une partie du courant cubiste une\nmani\u00e8re \u00e9l\u00e9gante d&#8217;utiliser toutes les couleurs*. <\/em>L\u2019autre peinture de 1989\nressort imm\u00e9diatement \u00ab&nbsp;plus contemporaine&nbsp;\u00bb, ou \u00ab&nbsp;fun&nbsp;\u00bb\ncomme le disaient les publicit\u00e9s de ces ann\u00e9es-l\u00e0. Le titre illustre bien la\nvolont\u00e9 d\u2019\u00eatre radicalement de son temps&nbsp;: \u00ab&nbsp;T 1989 K32&nbsp;\u00bb comme\nle num\u00e9ro d\u2019un colorant chimique moderne. Aussi, par ce qui pourrait \u00eatre vu\ncomme une d\u00e9sinvolture amusante (et amus\u00e9e&nbsp;?) dans sa fabrication, on\nretrouve l\u2019\u00e9poque&nbsp;: Hartung a de l\u2019humour dans le choix de son outil&#8230;\nune sulfateuse pour les vignes&nbsp;! La peinture employ\u00e9e appara\u00eet industrielle\net le geste fait finalement \u00e9cho \u00e0 un \u00ab&nbsp;dripping&nbsp;\u00bb de Jackson\nPollock, quarante ans plus t\u00f4t. Mais l\u2019effet \u00ab&nbsp;contemporain&nbsp;\u00bb tient \u00e0\nquelque chose de plus \u00ab&nbsp;pop&nbsp;\u00bb ou \u00ab&nbsp;rock&nbsp;\u00bb par&nbsp;ses\nteintes primaires juxtapos\u00e9es, un peu criardes &#8211; comme celles de bonbons\nindustriels &#8211;&nbsp; et surtout le\njaillissement plus puissant depuis sa sulfateuse, versus les \u00e9claboussures\nmanuelles de Pollock. <\/p>\n\n\n\n<p>Un peu plus loin dans l\u2019exposition, dans le film\nqu\u2019un jeune Alain Resnais tourna \u00e0 propos d\u2019Hans Hartung, le peintre dessine\navec des craies <em>Comt\u00e9<\/em> et diff\u00e9rents crayons sur du papier. On peut\nd\u00e9couvrir sa gestuelle*&nbsp;: r\u00e9guli\u00e8re, tonique, rel\u00e2ch\u00e9e, ample ou \u00e9triqu\u00e9e,\narrondie ou tranchante\u2026 C\u2019est elle qui, par le truchement du crayon devient\ndessin progressivement. Cela n\u2019est pas une expression d\u00e9sordonn\u00e9e, visc\u00e9rale,\no\u00f9 l\u2019artiste en \u00ab&nbsp;met partout&nbsp;\u00bb, comme le mythe li\u00e9 \u00e0 ce courant\nartistique le voudrait. Au contraire, et le documentaire va en ce sens,\nl\u2019expression physique d\u2019Hartung semble assez pond\u00e9r\u00e9e.<\/p>\n\n\n\n<p>\u00c0 un moment appara\u00eet son mat\u00e9riel et on voit, comme\nune palette, une bande de papier sur laquelle des tests au crayon gras ou sec\ndonnent l\u2019impression de diff\u00e9rentes valeurs et textures&nbsp;: une indication\nde plus que l\u2019\u0153uvre se construit progressivement de mani\u00e8re interactive entre\nle support et l\u2019artiste. On pourra retrouver, sur le dessin en cours de\nr\u00e9alisation dans la vid\u00e9o, certaines de ces textures o\u00f9 la craie effleure le\ngrain du papier pour un gris clair ou bien l\u2019aborde plus fermement pour une\nvaleur plus fonc\u00e9e.<\/p>\n\n\n\n<p>Son geste circulaire, puis plus droit, donne des\nformes rondes et carr\u00e9es. Les premi\u00e8res lignes sinueuses sont dessin\u00e9es avec un\ngeste lent assez l\u00e9ger. Lorsqu\u2019il attaque le dessin d\u2019un \u00ab&nbsp;angle&nbsp;\u00bb,\nil appuie davantage sur sa mine et acc\u00e9l\u00e8re. Pression musculaire et rythme font\ndessin. Il change sa main de place et son geste devient, sur la feuille, une\nsorte de point, comme une fin de phrase. <\/p>\n\n\n\n<p>Certaines orientations sont clairement lin\u00e9aires.\nUn plan du film montre l\u2019artiste en pied (jusqu\u2019alors on ne voyait que ses\nmains), et on peut discerner, en \u00e9tant attentif, l\u2019impulsion de son geste lent\net appliqu\u00e9, depuis la globalit\u00e9 de son corps. Cela conf\u00e8re \u00e0 la ligne une\nr\u00e9gularit\u00e9 et une stabilit\u00e9. Je pourrais entrer davantage dans le d\u00e9tail de\nl\u2019analyse du mouvement, mais ce sera sans doute l\u2019objet d\u2019un autre texte.<\/p>\n\n\n\n<p>Cette exposition et ce film constituent\nd\u2019excellents supports pour rappeler \u00e0 quel point la peinture et le dessin\nd\u00e9pendent du corps actif et ressentant, \u00ab&nbsp;Sensible*&nbsp;\u00bb, un corps qui\nn\u2019est pas qu\u2019un objet de la volont\u00e9 mais habit\u00e9\u2026 Comme le rappelle\nMerleau-Ponty\nnon sans humour : <em>\u00ab&nbsp;Le peintre \u00ab&nbsp;apporte son corps&nbsp;\u00bb,\ndit Val\u00e9ry. Et, en effet, on ne voit pas comment un Esprit pourrait\npeindre&nbsp;\u00bb <\/em>(Merleau-Ponty, 2000, p.16). <\/p>\n\n\n\n<p>* Le monologue du peintre, Georges Charbonnier Guy\nDirier, \u00e9diteur, 1980.<\/p>\n\n\n\n<p>* Des gris sont obtenus par des m\u00e9langes de\ncouleurs primaires, on parle alors de gris color\u00e9s.<\/p>\n\n\n\n<p>* Pour ce qui est du \u00ab&nbsp;Sensible&nbsp;\u00bb et de\nl\u2019analyse de la gestuelle dont est inspir\u00e9 cet article voir les ouvrages de\nBois, Danis&nbsp;: \u00ab&nbsp;La m\u00e9ditation pleine pr\u00e9sence&nbsp;\u00bb \u00e9ditions Eyrolles\n(2019) ou le moi renouvel\u00e9, Point d\u2019Appui (2006).<\/p>\n\n\n\n<p>* Merleau-Ponty, Maurice (2000),\n\u00ab&nbsp;l\u2019\u0153il et l\u2019esprit&nbsp;\u00bb, folio \/essais, Paris.<\/p>\n\n\n\n\n<script>\n  $( document ).ready(function() {\n  var pathDirections = {\n  view: 'M155.5,50l-50-50l-5,5l45,45l-45,45l5,5L155.5,50z M0,50l50,50l5-5L10,50L55,5l-5-5L0,50z',\n  exit: 'M55,50L5,0L0,5l45,45L0,95l5,5L55,50z M100.5,50l50,50l5-5l-45-45l45-45l-5-5L100.5,50z',\n};\n\nvar svgURI = 'http:\/\/www.w3.org\/2000\/svg';\n\nFlickity.FullscreenButton.prototype.createIcon = function() {\n  var svg = document.createElementNS( svgURI, 'svg');\n  svg.setAttribute( 'class', 'flickity-button-icon' );\n  svg.setAttribute( 'viewBox', '0 0 155.5 100' );\n  \/\/ path & direction\n  var path = document.createElementNS( svgURI, 'path');\n  var direction = pathDirections[ this.name ];\n  path.setAttribute( 'd', direction );\n  \/\/ put it together\n  svg.appendChild( path );\n  this.element.appendChild( svg );\n};\n});\n<\/script>\n\n\n\n<div class=\"mb-3\">\n<div class=\"carousel carousel-main invisible  carnum1298766791\" data-flickity='{\"lazyLoad\": 1, \"adaptiveHeight\": true, \"fullscreen\": true, \"imagesLoaded\": true, \"pageDots\": false,\"wrapAround\": true,\"arrowShape\":{\"x0\":10,\"x1\":60,\"y1\":50,\"x2\":65,\"y2\":45,\"x3\":20} }'>\n  \n    <div class=\"carousel-cell is-hidden\">\n      <div>\n      \t<figure>\n        <img itemprop=\"image\"   data-flickity-lazyload-srcset=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194156.jpg 720w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194156-300x240.jpg 360w\"  sizes=\"(min-width: 1024px) 720px, 360px\"  data-flickity-lazyload-src=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194156.jpg\" alt=\"\" \/>\n\n                <\/figure>\n      <\/div>\n    <\/div>\n    \n    <div class=\"carousel-cell is-hidden\">\n      <div>\n      \t<figure>\n        <img itemprop=\"image\"   data-flickity-lazyload-srcset=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_193721-1024x578.jpg 720w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_193721-300x169.jpg 360w\"  sizes=\"(min-width: 1024px) 720px, 360px\"  data-flickity-lazyload-src=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_193721-1024x578.jpg\" alt=\"\" \/>\n\n                <\/figure>\n      <\/div>\n    <\/div>\n    \n    <div class=\"carousel-cell is-hidden\">\n      <div>\n      \t<figure>\n        <img itemprop=\"image\"   data-flickity-lazyload-srcset=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194240-689x1024.jpg 720w, https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194240-202x300.jpg 360w\"  sizes=\"(min-width: 1024px) 720px, 360px\"  data-flickity-lazyload-src=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194240-689x1024.jpg\" alt=\"\" \/>\n\n                <\/figure>\n      <\/div>\n    <\/div>\n    <\/div>\n\n<div class=\"carousel carousel-nav\"\n  data-flickity='{ \"imagesLoaded\": true,\"lazyLoad\": true, \"asNavFor\": \".carnum1298766791\", \"contain\": true, \"pageDots\": false, \"prevNextButtons\": false }'>\n            <div class=\"item-thumbnail\">\n        <figure>\n          <img decoding=\"async\" class=\"carousel-cell\" src=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194156-150x150.jpg\" data-flickity-lazyload=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194156-150x150.jpg\" alt=\"Thumbnail of \" \/>\n        <\/figure>\n      <\/div>\n            <div class=\"item-thumbnail\">\n        <figure>\n          <img decoding=\"async\" class=\"carousel-cell\" src=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_193721-150x150.jpg\" data-flickity-lazyload=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_193721-150x150.jpg\" alt=\"Thumbnail of \" \/>\n        <\/figure>\n      <\/div>\n            <div class=\"item-thumbnail\">\n        <figure>\n          <img decoding=\"async\" class=\"carousel-cell\" src=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194240-150x150.jpg\" data-flickity-lazyload=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/IMG_20200330_194240-150x150.jpg\" alt=\"Thumbnail of \" \/>\n        <\/figure>\n      <\/div>\n        <\/div>\n<\/div>\n<style>\n  .invisible.flickity-enabled {visibility: visible !important}\n  <\/style>","protected":false},"featured_media":7096,"template":"","class_list":["post-7095","critique","type-critique","status-publish","has-post-thumbnail","hentry","categorie_crit-peinture"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un Hans Hartung fun et gestuel ! - Art Interview<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Hans Hartung fun et gestuel ! - Art Interview\" \/>\n<meta property=\"og:description\" content=\"L\u2019oeil du peintre Marc Goldstain Quelques r\u00e9flexions que je partage avec vous apr\u00e8s avoir visit\u00e9 l\u2019exposition \u00ab&nbsp;Hans Hartung et la fabrique du geste&nbsp;\u00bb au Mus\u00e9e d\u2019art moderne de la ville de Paris, fra\u00eechement r\u00e9ouvert. Hans Hartung y appara\u00eet d\u00e9j\u00e0 comme un artiste contemporain sous certains aspects comme le choix de ses couleurs et de ses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/\" \/>\n<meta property=\"og:site_name\" content=\"Art Interview\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/artinterviewmagazine\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-31T12:05:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/image1-hh_1_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/\",\"url\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/\",\"name\":\"Un Hans Hartung fun et gestuel ! - Art Interview\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image1-hh_1_1.jpg\",\"datePublished\":\"2020-04-01T14:09:09+00:00\",\"dateModified\":\"2022-12-31T12:05:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image1-hh_1_1.jpg\",\"contentUrl\":\"https:\\\/\\\/artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/image1-hh_1_1.jpg\",\"width\":400,\"height\":294},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/un-hans-hartung-fun-et-gestuel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/artinterview.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Critique\",\"item\":\"https:\\\/\\\/artinterview.com\\\/en\\\/critique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un Hans Hartung fun et gestuel !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/artinterview.com\\\/en\\\/\",\"name\":\"Art Interview\",\"description\":\"Because art is everywhere\",\"publisher\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artinterview.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#organization\",\"name\":\"Art Interview\",\"url\":\"https:\\\/\\\/artinterview.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/5c337d0326d4de5bde65529a.png\",\"contentUrl\":\"https:\\\/\\\/www.artinterview.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/5c337d0326d4de5bde65529a.png\",\"width\":3397,\"height\":2374,\"caption\":\"Art Interview\"},\"image\":{\"@id\":\"https:\\\/\\\/artinterview.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/artinterviewmagazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/art.interview\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCjnghW7ZyDAts9yGi-Ic19w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un Hans Hartung fun et gestuel ! - Art Interview","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/","og_locale":"en_US","og_type":"article","og_title":"Un Hans Hartung fun et gestuel ! - Art Interview","og_description":"L\u2019oeil du peintre Marc Goldstain Quelques r\u00e9flexions que je partage avec vous apr\u00e8s avoir visit\u00e9 l\u2019exposition \u00ab&nbsp;Hans Hartung et la fabrique du geste&nbsp;\u00bb au Mus\u00e9e d\u2019art moderne de la ville de Paris, fra\u00eechement r\u00e9ouvert. Hans Hartung y appara\u00eet d\u00e9j\u00e0 comme un artiste contemporain sous certains aspects comme le choix de ses couleurs et de ses [&hellip;]","og_url":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/","og_site_name":"Art Interview","article_publisher":"https:\/\/www.facebook.com\/artinterviewmagazine\/","article_modified_time":"2022-12-31T12:05:29+00:00","og_image":[{"width":400,"height":294,"url":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/image1-hh_1_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/","url":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/","name":"Un Hans Hartung fun et gestuel ! - Art Interview","isPartOf":{"@id":"https:\/\/artinterview.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/#primaryimage"},"image":{"@id":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/#primaryimage"},"thumbnailUrl":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/image1-hh_1_1.jpg","datePublished":"2020-04-01T14:09:09+00:00","dateModified":"2022-12-31T12:05:29+00:00","breadcrumb":{"@id":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/#primaryimage","url":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/image1-hh_1_1.jpg","contentUrl":"https:\/\/artinterview.com\/wp-content\/uploads\/2020\/04\/image1-hh_1_1.jpg","width":400,"height":294},{"@type":"BreadcrumbList","@id":"https:\/\/artinterview.com\/en\/critique\/un-hans-hartung-fun-et-gestuel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/artinterview.com\/en\/"},{"@type":"ListItem","position":2,"name":"Critique","item":"https:\/\/artinterview.com\/en\/critique\/"},{"@type":"ListItem","position":3,"name":"Un Hans Hartung fun et gestuel !"}]},{"@type":"WebSite","@id":"https:\/\/artinterview.com\/en\/#website","url":"https:\/\/artinterview.com\/en\/","name":"Art Interview","description":"Because art is everywhere","publisher":{"@id":"https:\/\/artinterview.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artinterview.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/artinterview.com\/en\/#organization","name":"Art Interview","url":"https:\/\/artinterview.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artinterview.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.artinterview.com\/wp-content\/uploads\/2020\/04\/5c337d0326d4de5bde65529a.png","contentUrl":"https:\/\/www.artinterview.com\/wp-content\/uploads\/2020\/04\/5c337d0326d4de5bde65529a.png","width":3397,"height":2374,"caption":"Art Interview"},"image":{"@id":"https:\/\/artinterview.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/artinterviewmagazine\/","https:\/\/www.instagram.com\/art.interview\/","https:\/\/www.youtube.com\/channel\/UCjnghW7ZyDAts9yGi-Ic19w"]}]}},"_links":{"self":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/critique\/7095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/critique"}],"about":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/types\/critique"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/media\/7096"}],"wp:attachment":[{"href":"https:\/\/artinterview.com\/en\/wp-json\/wp\/v2\/media?parent=7095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}